{"id":274,"count":1,"description":"","link":"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/","name":"Vigo","slug":"vigo","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Vigo Archive - Lindenhausen-weil Reisen Spa\u00df macht<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vigo Archive - Lindenhausen-weil Reisen Spa\u00df macht\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/\" \/>\n<meta property=\"og:site_name\" content=\"Lindenhausen-weil Reisen Spa\u00df macht\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Maxilinde\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/\",\"url\":\"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/\",\"name\":\"Vigo Archive - Lindenhausen-weil Reisen Spa\u00df macht\",\"isPartOf\":{\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#website\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/#breadcrumb\"},\"inLanguage\":\"de\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.lindenhausen.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vigo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#website\",\"url\":\"https:\/\/www.lindenhausen.de\/blog\/\",\"name\":\"Lindenhausen-weil Reisen Spa\u00df macht\",\"description\":\"Reisen und Kreuzfahrten, Reiseberichte, Kreuzfahrtforum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lindenhausen.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vigo Archive - Lindenhausen-weil Reisen Spa\u00df macht","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/","og_locale":"de_DE","og_type":"article","og_title":"Vigo Archive - Lindenhausen-weil Reisen Spa\u00df macht","og_url":"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/","og_site_name":"Lindenhausen-weil Reisen Spa\u00df macht","twitter_card":"summary_large_image","twitter_site":"@Maxilinde","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/","url":"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/","name":"Vigo Archive - Lindenhausen-weil Reisen Spa\u00df macht","isPartOf":{"@id":"https:\/\/www.lindenhausen.de\/blog\/#website"},"breadcrumb":{"@id":"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/#breadcrumb"},"inLanguage":"de"},{"@type":"BreadcrumbList","@id":"http:\/\/www.lindenhausen.de\/blog\/tag\/vigo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lindenhausen.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Vigo"}]},{"@type":"WebSite","@id":"https:\/\/www.lindenhausen.de\/blog\/#website","url":"https:\/\/www.lindenhausen.de\/blog\/","name":"Lindenhausen-weil Reisen Spa\u00df macht","description":"Reisen und Kreuzfahrten, Reiseberichte, Kreuzfahrtforum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lindenhausen.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/tags\/274"}],"collection":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/posts?tags=274"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}