{"id":366,"date":"2015-04-13T08:55:16","date_gmt":"2015-04-13T06:55:16","guid":{"rendered":"http:\/\/www.lindenhausen.de\/blog\/?p=366"},"modified":"2015-04-13T12:08:27","modified_gmt":"2015-04-13T10:08:27","slug":"costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage","status":"publish","type":"post","link":"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/","title":{"rendered":"Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt-Umfrage"},"content":{"rendered":"<p>Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt<br \/>\nNachdem in der letzten Zeit die Wellen ab und an hochschlagen w\u00e4re es doch sch\u00f6n mal sachlich zusammenzutragen was uns an Costa gef\u00e4llt und was auch nicht.<br \/>\nEs gibt Kritiken, die kann ich nachvollziehen, es gibt welche, da bleibt nur Kopfsch\u00fctteln (Italiener auf einem Italienischen Schiff sind nunmal genauso normal wie Deutsche auf AIDA ;))<br \/>\nAuch wenn wir hier einige Fans sind, sind wir ja nicht blind und taub, auch die manchmal unterstellte rosarote Brille wird oft abgesetzt.<\/p>\n<p>Ich bitte darum sachlich zu bleiben, nach beiden Seiten, da ich die Absicht habe das Ergebnis hier Costa auch zukommen zu lassen.<br \/>\nDie Reederei darf Lob und Tadel schonmal lesen und h\u00f6ren und ich hoffe das es sie auch interessiert.<br \/>\nAlso macht mit \ud83d\ude42<br \/>\n<a href=\"http:\/\/lindenhausen.de\/Forum\/index.php?page=Thread&amp;threadID=423\" target=\"_blank\">zur Umfrage<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt Nachdem in der letzten Zeit die Wellen ab und an hochschlagen w\u00e4re es doch sch\u00f6n mal sachlich zusammenzutragen was uns an Costa gef\u00e4llt und was auch nicht. Es gibt Kritiken, die kann ich nachvollziehen, es gibt welche, da bleibt nur Kopfsch\u00fctteln (Italiener auf &hellip; <a href=\"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/\" class=\"more-link\"><span class=\"screen-reader-text\">Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt-Umfrage<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"categories":[1],"tags":[7,10,9,8],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt-Umfrage - Lindenhausen-weil Reisen Spa\u00df macht<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt-Umfrage - Lindenhausen-weil Reisen Spa\u00df macht\" \/>\n<meta property=\"og:description\" content=\"Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt Nachdem in der letzten Zeit die Wellen ab und an hochschlagen w\u00e4re es doch sch\u00f6n mal sachlich zusammenzutragen was uns an Costa gef\u00e4llt und was auch nicht. Es gibt Kritiken, die kann ich nachvollziehen, es gibt welche, da bleibt nur Kopfsch\u00fctteln (Italiener auf &hellip; Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt-Umfrage weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/\" \/>\n<meta property=\"og:site_name\" content=\"Lindenhausen-weil Reisen Spa\u00df macht\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/Lindenhausen\/\" \/>\n<meta property=\"article:published_time\" content=\"2015-04-13T06:55:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2015-04-13T10:08:27+00:00\" \/>\n<meta name=\"author\" content=\"Michaela\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Maxilinde\" \/>\n<meta name=\"twitter:site\" content=\"@Maxilinde\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Michaela\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/\",\"url\":\"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/\",\"name\":\"Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt-Umfrage - Lindenhausen-weil Reisen Spa\u00df macht\",\"isPartOf\":{\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#website\"},\"datePublished\":\"2015-04-13T06:55:16+00:00\",\"dateModified\":\"2015-04-13T10:08:27+00:00\",\"author\":{\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#\/schema\/person\/4dd3652ec1fb54c2be72afac7bb777b0\"},\"breadcrumb\":{\"@id\":\"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.lindenhausen.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt-Umfrage\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#website\",\"url\":\"https:\/\/www.lindenhausen.de\/blog\/\",\"name\":\"Lindenhausen-weil Reisen Spa\u00df macht\",\"description\":\"Reisen und Kreuzfahrten, Reiseberichte, Kreuzfahrtforum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lindenhausen.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#\/schema\/person\/4dd3652ec1fb54c2be72afac7bb777b0\",\"name\":\"Michaela\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#\/schema\/person\/image\/\",\"url\":\"http:\/\/2.gravatar.com\/avatar\/26d4ec83ac81670945d6f23a21d88fcf?s=96&d=mm&r=g\",\"contentUrl\":\"http:\/\/2.gravatar.com\/avatar\/26d4ec83ac81670945d6f23a21d88fcf?s=96&d=mm&r=g\",\"caption\":\"Michaela\"},\"url\":\"http:\/\/www.lindenhausen.de\/blog\/author\/admin\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt-Umfrage - Lindenhausen-weil Reisen Spa\u00df macht","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/","og_locale":"de_DE","og_type":"article","og_title":"Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt-Umfrage - Lindenhausen-weil Reisen Spa\u00df macht","og_description":"Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt Nachdem in der letzten Zeit die Wellen ab und an hochschlagen w\u00e4re es doch sch\u00f6n mal sachlich zusammenzutragen was uns an Costa gef\u00e4llt und was auch nicht. Es gibt Kritiken, die kann ich nachvollziehen, es gibt welche, da bleibt nur Kopfsch\u00fctteln (Italiener auf &hellip; Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt-Umfrage weiterlesen &rarr;","og_url":"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/","og_site_name":"Lindenhausen-weil Reisen Spa\u00df macht","article_publisher":"http:\/\/www.facebook.com\/Lindenhausen\/","article_published_time":"2015-04-13T06:55:16+00:00","article_modified_time":"2015-04-13T10:08:27+00:00","author":"Michaela","twitter_card":"summary_large_image","twitter_creator":"@Maxilinde","twitter_site":"@Maxilinde","twitter_misc":{"Verfasst von":"Michaela","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/","url":"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/","name":"Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt-Umfrage - Lindenhausen-weil Reisen Spa\u00df macht","isPartOf":{"@id":"https:\/\/www.lindenhausen.de\/blog\/#website"},"datePublished":"2015-04-13T06:55:16+00:00","dateModified":"2015-04-13T10:08:27+00:00","author":{"@id":"https:\/\/www.lindenhausen.de\/blog\/#\/schema\/person\/4dd3652ec1fb54c2be72afac7bb777b0"},"breadcrumb":{"@id":"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.lindenhausen.de\/blog\/costa-kreuzfahrt-was-ich-an-costa-mag-und-was-mir-nicht-gefaellt-umfrage\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lindenhausen.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Costa Kreuzfahrt- was ich an Costa mag und was mir nicht gef\u00e4llt-Umfrage"}]},{"@type":"WebSite","@id":"https:\/\/www.lindenhausen.de\/blog\/#website","url":"https:\/\/www.lindenhausen.de\/blog\/","name":"Lindenhausen-weil Reisen Spa\u00df macht","description":"Reisen und Kreuzfahrten, Reiseberichte, Kreuzfahrtforum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lindenhausen.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/www.lindenhausen.de\/blog\/#\/schema\/person\/4dd3652ec1fb54c2be72afac7bb777b0","name":"Michaela","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.lindenhausen.de\/blog\/#\/schema\/person\/image\/","url":"http:\/\/2.gravatar.com\/avatar\/26d4ec83ac81670945d6f23a21d88fcf?s=96&d=mm&r=g","contentUrl":"http:\/\/2.gravatar.com\/avatar\/26d4ec83ac81670945d6f23a21d88fcf?s=96&d=mm&r=g","caption":"Michaela"},"url":"http:\/\/www.lindenhausen.de\/blog\/author\/admin\/"}]}},"_links":{"self":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/posts\/366"}],"collection":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/comments?post=366"}],"version-history":[{"count":2,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/posts\/366\/revisions"}],"predecessor-version":[{"id":370,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/posts\/366\/revisions\/370"}],"wp:attachment":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/media?parent=366"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/categories?post=366"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/tags?post=366"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}