{"id":381,"date":"2015-04-17T15:09:14","date_gmt":"2015-04-17T13:09:14","guid":{"rendered":"http:\/\/www.lindenhausen.de\/blog\/?page_id=381"},"modified":"2018-05-20T12:16:42","modified_gmt":"2018-05-20T10:16:42","slug":"datenschutzerklaerung","status":"publish","type":"page","link":"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/","title":{"rendered":"Datenschutzerkl\u00e4rung"},"content":{"rendered":"<p>&nbsp;<\/p>\n<p>1. Datenschutz auf einen Blick<br \/>\nAllgemeine Hinweise<br \/>\nDie folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung.<\/p>\n<p>Datenerfassung auf unserer Website<br \/>\nWer ist verantwortlich f\u00fcr die Datenerfassung auf dieser Website?<\/p>\n<p>Die Datenverarbeitung auf dieser Website erfolgt durch den Websitebetreiber. Dessen Kontaktdaten k\u00f6nnen Sie dem Impressum dieser Website entnehmen.<\/p>\n<p>Wie erfassen wir Ihre Daten?<\/p>\n<p>Ihre Daten werden zum einen dadurch erhoben, dass Sie uns diese mitteilen. Hierbei kann es sich z.B. um Daten handeln, die Sie in ein Kontaktformular eingeben.<\/p>\n<p>Andere Daten werden automatisch beim Besuch der Website durch unsere IT-Systeme erfasst. Das sind vor allem technische Daten (z.B. Internetbrowser, Betriebssystem oder Uhrzeit des Seitenaufrufs). Die Erfassung dieser Daten erfolgt automatisch, sobald Sie unsere Website betreten.<\/p>\n<p>Wof\u00fcr nutzen wir Ihre Daten?<\/p>\n<p>Ein Teil der Daten wird erhoben, um eine fehlerfreie Bereitstellung der Website zu gew\u00e4hrleisten. Andere Daten k\u00f6nnen zur Analyse Ihres Nutzerverhaltens verwendet werden.<\/p>\n<p>Welche Rechte haben Sie bez\u00fcglich Ihrer Daten?<\/p>\n<p>Sie haben jederzeit das Recht unentgeltlich Auskunft \u00fcber Herkunft, Empf\u00e4nger und Zweck Ihrer gespeicherten personenbezogenen Daten zu erhalten. Sie haben au\u00dferdem ein Recht, die Berichtigung, Sperrung oder L\u00f6schung dieser Daten zu verlangen. Hierzu sowie zu weiteren Fragen zum Thema Datenschutz k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden. Des Weiteren steht Ihnen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu.<\/p>\n<p>2. Allgemeine Hinweise und Pflichtinformationen<br \/>\nDatenschutz<br \/>\nDie Betreiber dieser Seiten nehmen den Schutz Ihrer pers\u00f6nlichen Daten sehr ernst. Wir behandeln Ihre personenbezogenen Daten vertraulich und entsprechend der gesetzlichen Datenschutzvorschriften sowie dieser Datenschutzerkl\u00e4rung.<\/p>\n<p>Wenn Sie diese Website benutzen, werden verschiedene personenbezogene Daten erhoben. Personenbezogene Daten sind Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Die vorliegende Datenschutzerkl\u00e4rung erl\u00e4utert, welche Daten wir erheben und wof\u00fcr wir sie nutzen. Sie erl\u00e4utert auch, wie und zu welchem Zweck das geschieht.<\/p>\n<p>Wir weisen darauf hin, dass die Daten\u00fcbertragung im Internet (z.B. bei der Kommunikation per E-Mail) Sicherheitsl\u00fccken aufweisen kann. Ein l\u00fcckenloser Schutz der Daten vor dem Zugriff durch Dritte ist nicht m\u00f6glich.<\/p>\n<p>Hinweis zur verantwortlichen Stelle<br \/>\nDie verantwortliche Stelle f\u00fcr die Datenverarbeitung auf dieser Website ist:<\/p>\n<p>Michaela Linde<\/p>\n<p>Giselastra\u00dfe 30<\/p>\n<p>93309 Kelheim<\/p>\n<p>Telefon: 09441-682557<br \/>\nE-Mail: info@lindenhausen.de<\/p>\n<p>Verantwortliche Stelle ist die nat\u00fcrliche oder juristische Person, die allein oder gemeinsam mit anderen \u00fcber die Zwecke und Mittel der Verarbeitung von personenbezogenen Daten (z.B. Namen, E-Mail-Adressen o. \u00c4.) entscheidet.<\/p>\n<p>Widerruf Ihrer Einwilligung zur Datenverarbeitung<br \/>\nViele Datenverarbeitungsvorg\u00e4nge sind nur mit Ihrer ausdr\u00fccklichen Einwilligung m\u00f6glich. Sie k\u00f6nnen eine bereits erteilte Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an uns. Die Rechtm\u00e4\u00dfigkeit der bis zum Widerruf erfolgten Datenverarbeitung bleibt vom Widerruf unber\u00fchrt.<\/p>\n<p>Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde<br \/>\nIm Falle datenschutzrechtlicher Verst\u00f6\u00dfe steht dem Betroffenen ein Beschwerderecht bei der zust\u00e4ndigen Aufsichtsbeh\u00f6rde zu. Zust\u00e4ndige Aufsichtsbeh\u00f6rde in datenschutzrechtlichen Fragen ist der Landesdatenschutzbeauftragte des Bundeslandes, in dem unser Unternehmen seinen Sitz hat. Eine Liste der Datenschutzbeauftragten sowie deren Kontaktdaten k\u00f6nnen folgendem Link entnommen werden: https:\/\/www.bfdi.bund.de\/DE\/Infothek\/Anschriften_Links\/anschriften_links-node.html.<\/p>\n<p>Recht auf Daten\u00fcbertragbarkeit<br \/>\nSie haben das Recht, Daten, die wir auf Grundlage Ihrer Einwilligung oder in Erf\u00fcllung eines Vertrags automatisiert verarbeiten, an sich oder an einen Dritten in einem g\u00e4ngigen, maschinenlesbaren Format aush\u00e4ndigen zu lassen. Sofern Sie die direkte \u00dcbertragung der Daten an einen anderen Verantwortlichen verlangen, erfolgt dies nur, soweit es technisch machbar ist.<\/p>\n<p>Auskunft, Sperrung, L\u00f6schung<br \/>\nSie haben im Rahmen der geltenden gesetzlichen Bestimmungen jederzeit das Recht auf unentgeltliche Auskunft \u00fcber Ihre gespeicherten personenbezogenen Daten, deren Herkunft und Empf\u00e4nger und den Zweck der Datenverarbeitung und ggf. ein Recht auf Berichtigung, Sperrung oder L\u00f6schung dieser Daten. Hierzu sowie zu weiteren Fragen zum Thema personenbezogene Daten k\u00f6nnen Sie sich jederzeit unter der im Impressum angegebenen Adresse an uns wenden.<\/p>\n<p>Widerspruch gegen Werbe-Mails<br \/>\nDer Nutzung von im Rahmen der Impressumspflicht ver\u00f6ffentlichten Kontaktdaten zur \u00dcbersendung von nicht ausdr\u00fccklich angeforderter Werbung und Informationsmaterialien wird hiermit widersprochen. Die Betreiber der Seiten behalten sich ausdr\u00fccklich rechtliche Schritte im Falle der unverlangten Zusendung von Werbeinformationen, etwa durch Spam-E-Mails, vor.<\/p>\n<p>3. Datenerfassung auf unserer Website<br \/>\nCookies<br \/>\nDie Internetseiten verwenden teilweise so genannte Cookies. Cookies richten auf Ihrem Rechner keinen Schaden an und enthalten keine Viren. Cookies dienen dazu, unser Angebot nutzerfreundlicher, effektiver und sicherer zu machen. Cookies sind kleine Textdateien, die auf Ihrem Rechner abgelegt werden und die Ihr Browser speichert.<\/p>\n<p>Die meisten der von uns verwendeten Cookies sind so genannte \u201cSession-Cookies\u201d. Sie werden nach Ende Ihres Besuchs automatisch gel\u00f6scht. Andere Cookies bleiben auf Ihrem Endger\u00e4t gespeichert bis Sie diese l\u00f6schen. Diese Cookies erm\u00f6glichen es uns, Ihren Browser beim n\u00e4chsten Besuch wiederzuerkennen.<\/p>\n<p>Sie k\u00f6nnen Ihren Browser so einstellen, dass Sie \u00fcber das Setzen von Cookies informiert werden und Cookies nur im Einzelfall erlauben, die Annahme von Cookies f\u00fcr bestimmte F\u00e4lle oder generell ausschlie\u00dfen sowie das automatische L\u00f6schen der Cookies beim Schlie\u00dfen des Browser aktivieren. Bei der Deaktivierung von Cookies kann die Funktionalit\u00e4t dieser Website eingeschr\u00e4nkt sein.<\/p>\n<p>Cookies, die zur Durchf\u00fchrung des elektronischen Kommunikationsvorgangs oder zur Bereitstellung bestimmter, von Ihnen erw\u00fcnschter Funktionen (z.B. Warenkorbfunktion) erforderlich sind, werden auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO gespeichert. Der Websitebetreiber hat ein berechtigtes Interesse an der Speicherung von Cookies zur technisch fehlerfreien und optimierten Bereitstellung seiner Dienste. Soweit andere Cookies (z.B. Cookies zur Analyse Ihres Surfverhaltens) gespeichert werden, werden diese in dieser Datenschutzerkl\u00e4rung gesondert behandelt.<\/p>\n<p>Server-Log-Dateien<br \/>\nDer Provider der Seiten erhebt und speichert automatisch Informationen in so genannten Server-Log-Dateien, die Ihr Browser automatisch an uns \u00fcbermittelt. Dies sind:<\/p>\n<p>Browsertyp und Browserversion<br \/>\nverwendetes Betriebssystem<br \/>\nReferrer URL<br \/>\nHostname des zugreifenden Rechners<br \/>\nUhrzeit der Serveranfrage<br \/>\nIP-Adresse<br \/>\nEine Zusammenf\u00fchrung dieser Daten mit anderen Datenquellen wird nicht vorgenommen.<\/p>\n<p>Grundlage f\u00fcr die Datenverarbeitung ist Art. 6 Abs. 1 lit. b DSGVO, der die Verarbeitung von Daten zur Erf\u00fcllung eines Vertrags oder vorvertraglicher Ma\u00dfnahmen gestattet.<\/p>\n<p>Registrierung auf dieser Website<br \/>\nSie k\u00f6nnen sich auf unserer Website registrieren, um zus\u00e4tzliche Funktionen auf der Seite zu nutzen. Die dazu eingegebenen Daten verwenden wir nur zum Zwecke der Nutzung des jeweiligen Angebotes oder Dienstes, f\u00fcr den Sie sich registriert haben. Die bei der Registrierung abgefragten Pflichtangaben m\u00fcssen vollst\u00e4ndig angegeben werden. Anderenfalls werden wir die Registrierung ablehnen.<\/p>\n<p>F\u00fcr wichtige \u00c4nderungen etwa beim Angebotsumfang oder bei technisch notwendigen \u00c4nderungen nutzen wir die bei der Registrierung angegebene E-Mail-Adresse, um Sie auf diesem Wege zu informieren.<\/p>\n<p>Die Verarbeitung der bei der Registrierung eingegebenen Daten erfolgt auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO). Sie k\u00f6nnen eine von Ihnen erteilte Einwilligung jederzeit widerrufen. Dazu reicht eine formlose Mitteilung per E-Mail an uns. Die Rechtm\u00e4\u00dfigkeit der bereits erfolgten Datenverarbeitung bleibt vom Widerruf unber\u00fchrt.<\/p>\n<p>Die bei der Registrierung erfassten Daten werden von uns gespeichert, solange Sie auf unserer Website registriert sind und werden anschlie\u00dfend gel\u00f6scht. Gesetzliche Aufbewahrungsfristen bleiben unber\u00fchrt.<\/p>\n<p>Registrierung mit Facebook Connect-wird auf dieser Seite nicht angeboten<br \/>\nStatt einer direkten Registrierung auf unserer Website k\u00f6nnen Sie sich mit Facebook Connect registrieren. Anbieter dieses Dienstes ist die Facebook Ireland Limited, 4 Grand Canal Square, Dublin 2, Irland.<\/p>\n<p>Wenn Sie sich f\u00fcr die Registrierung mit Facebook Connect entscheiden, werden Sie automatisch auf die Plattform von Facebook weitergeleitet. Dort k\u00f6nnen Sie sich mit Ihren Nutzungsdaten anmelden. Dadurch wird Ihr Facebook-Profil mit unserer Website bzw. unseren Diensten verkn\u00fcpft. Durch diese Verkn\u00fcpfung erhalten wir Zugriff auf Ihre bei Facebook hinterlegten Daten. Dies sind vor allem:<\/p>\n<p>Facebook-Name<br \/>\nFacebook-Profilbild<br \/>\nbei Facebook hinterlegte E-Mail-Adresse<br \/>\nFacebook-ID<br \/>\nGeburtstag<br \/>\nGeschlecht<br \/>\nLand<br \/>\nDiese Daten werden zur Einrichtung, Bereitstellung und Personalisierung Ihres Accounts genutzt.<\/p>\n<p>Weitere Informationen finden Sie in den Facebook-Nutzungsbedingungen und den Facebook-Datenschutzbestimmungen. Diese finden Sie unter: https:\/\/de-de.facebook.com\/about\/privacy\/ und https:\/\/www.facebook.com\/legal\/terms\/.<\/p>\n<p>Registrierung mit Google+-wird auf dieser Seite nicht angeboten<br \/>\nStatt einer direkten Registrierung auf unserer Website k\u00f6nnen Sie sich mit Google+ registrieren. Anbieter dieses Dienstes ist die Google LLC, 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA.<\/p>\n<p>Wenn Sie sich f\u00fcr die Registrierung mit Google+ entscheiden, werden Sie automatisch auf die Plattform von Google+ weitergeleitet. Dort k\u00f6nnen Sie sich mit Ihren Nutzungsdaten anmelden. Dadurch wird Ihr Google+-Profil mit unserer Website bzw. unseren Diensten verkn\u00fcpft. Durch diese Verkn\u00fcpfung erhalten wir Zugriff auf Ihre bei Google+ hinterlegten Daten. Dies sind vor allem:<\/p>\n<p>Google+-Name<br \/>\nGoogle+-Profilbild<br \/>\nbei Google+ hinterlegte E-Mail-Adresse<br \/>\nGoogle+-ID<br \/>\nGeburtstag<br \/>\nGeschlecht<br \/>\nLand<br \/>\nDiese Daten werden zur Einrichtung, Bereitstellung und Personalisierung Ihres Accounts genutzt.<\/p>\n<p>Weitere Informationen finden Sie in den Google-Nutzungsbedingungen, Google+-Nutzungsbedingungen und den Google-Datenschutzbestimmungen. Diese finden Sie unter: https:\/\/policies.google.com\/terms?hl=de, https:\/\/www.google.com\/intl\/de\/+\/policy\/pagesterms.html und https:\/\/policies.google.com\/privacy?hl=de.<\/p>\n<p>Registrierung mit Twitter-wird auf dieser Seite nicht angeboten<br \/>\nStatt einer direkten Registrierung auf unserer Website k\u00f6nnen Sie sich mit Twitter registrieren. Anbieter dieses Dienstes ist die Twitter Inc., 1355 Market Street, Suite 900, San Francisco, CA 94103, USA.<\/p>\n<p>Wenn Sie sich f\u00fcr die Registrierung mit Twitter entscheiden, werden Sie automatisch auf die Plattform von Twitter weitergeleitet. Dort k\u00f6nnen Sie sich mit Ihren Nutzungsdaten anmelden. Dadurch wird Ihr Twitter-Profil mit unserer Website bzw. unseren Diensten verkn\u00fcpft. Durch diese Verkn\u00fcpfung erhalten wir Zugriff auf Ihre bei Twitter hinterlegten Daten. Dies sind vor allem:<\/p>\n<p>Twitter-Name<br \/>\nTwitter-Profilbild<br \/>\nbei Twitter hinterlegte E-Mail-Adresse<br \/>\nTwitter-ID<br \/>\nGeburtstag<br \/>\nGeschlecht<br \/>\nLand<br \/>\nDiese Daten werden zur Einrichtung, Bereitstellung und Personalisierung Ihres Accounts genutzt.<\/p>\n<p>Weitere Informationen finden Sie in den Twitter-Nutzungsbedingungen und den Twitter-Datenschutzbestimmungen. Diese finden Sie unter: https:\/\/twitter.com\/de\/tos und https:\/\/twitter.com\/de\/privacy.<\/p>\n<p>Registrierung mit GitHub-wird auf dieser Seite nicht angeboten<br \/>\nStatt einer direkten Registrierung auf unserer Website k\u00f6nnen Sie sich mit GitHub registrieren. Anbieter dieses Dienstes ist die GitHub, Inc, 88 Colin P Kelly Jr St, San Francisco, CA 94107, USA.<\/p>\n<p>Wenn Sie sich f\u00fcr die Registrierung mit GitHub entscheiden, werden Sie automatisch auf die Plattform von GitHub weitergeleitet. Dort k\u00f6nnen Sie sich mit Ihren Nutzungsdaten anmelden. Dadurch wird Ihr GitHub-Profil mit unserer Website bzw. unseren Diensten verkn\u00fcpft. Durch diese Verkn\u00fcpfung erhalten wir Zugriff auf Ihre bei GitHub hinterlegten Daten. Dies sind vor allem:<\/p>\n<p>GitHub-Name<br \/>\nGitHub-Profilbild<br \/>\nbei GitHub hinterlegte E-Mail-Adresse<br \/>\nGitHub-ID<br \/>\nGeburtstag<br \/>\nGeschlecht<br \/>\nLand<br \/>\nDiese Daten werden zur Einrichtung, Bereitstellung und Personalisierung Ihres Accounts genutzt.<\/p>\n<p>Weitere Informationen finden Sie in den GitHub-Nutzungsbedingungen und den GitHub-Datenschutzbestimmungen. Diese finden Sie unter: https:\/\/help.github.com\/articles\/github-terms-of-service\/ und https:\/\/help.github.com\/articles\/github-privacy-statement\/.<\/p>\n<p>Verarbeiten von Daten (Kunden- und Vertragsdaten)<br \/>\nWir erheben, verarbeiten und nutzen personenbezogene Daten nur, soweit sie f\u00fcr die Begr\u00fcndung, inhaltliche Ausgestaltung oder \u00c4nderung des Rechtsverh\u00e4ltnisses erforderlich sind (Bestandsdaten). Dies erfolgt auf Grundlage von Art. 6 Abs. 1 lit. b DSGVO, der die Verarbeitung von Daten zur Erf\u00fcllung eines Vertrags oder vorvertraglicher Ma\u00dfnahmen gestattet. Personenbezogene Daten \u00fcber die Inanspruchnahme unserer Internetseiten (Nutzungsdaten) erheben, verarbeiten und nutzen wir nur, soweit dies erforderlich ist, um dem Nutzer die Inanspruchnahme des Dienstes zu erm\u00f6glichen oder abzurechnen.<\/p>\n<p>Die erhobenen Kundendaten werden nach Abschluss des Auftrags oder Beendigung der Gesch\u00e4ftsbeziehung gel\u00f6scht. Gesetzliche Aufbewahrungsfristen bleiben unber\u00fchrt.<\/p>\n<p>Daten\u00fcbermittlung bei Vertragsschluss f\u00fcr Dienstleistungen und digitale Inhalte<br \/>\nWir \u00fcbermitteln personenbezogene Daten an Dritte nur dann, wenn dies im Rahmen der Vertragsabwicklung notwendig ist, etwa an das mit der Zahlungsabwicklung beauftragte Kreditinstitut.<\/p>\n<p>Eine weitergehende \u00dcbermittlung der Daten erfolgt nicht bzw. nur dann, wenn Sie der \u00dcbermittlung ausdr\u00fccklich zugestimmt haben. Eine Weitergabe Ihrer Daten an Dritte ohne ausdr\u00fcckliche Einwilligung, etwa zu Zwecken der Werbung, erfolgt nicht.<\/p>\n<p>Grundlage f\u00fcr die Datenverarbeitung ist Art. 6 Abs. 1 lit. b DSGVO, der die Verarbeitung von Daten zur Erf\u00fcllung eines Vertrags oder vorvertraglicher Ma\u00dfnahmen gestattet.<\/p>\n<p>4. Analyse Tools und Werbung<br \/>\nGoogle reCAPTCHA<br \/>\nWir nutzen \u201cGoogle reCAPTCHA\u201d (im Folgenden \u201creCAPTCHA\u201d) auf unseren Websites. Anbieter ist die Google Inc., 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA (\u201cGoogle\u201d).<\/p>\n<p>Mit reCAPTCHA soll \u00fcberpr\u00fcft werden, ob die Dateneingabe auf unseren Websites (z.B. in einem Kontaktformular) durch einen Menschen oder durch ein automatisiertes Programm erfolgt. Hierzu analysiert reCAPTCHA das Verhalten des Websitebesuchers anhand verschiedener Merkmale. Diese Analyse beginnt automatisch, sobald der Websitebesucher die Website betritt. Zur Analyse wertet reCAPTCHA verschiedene Informationen aus (z.B. IP-Adresse, Verweildauer des Websitebesuchers auf der Website oder vom Nutzer get\u00e4tigte Mausbewegungen). Die bei der Analyse erfassten Daten werden an Google weitergeleitet.<\/p>\n<p>Die reCAPTCHA-Analysen laufen vollst\u00e4ndig im Hintergrund. Websitebesucher werden nicht darauf hingewiesen, dass eine Analyse stattfindet.<\/p>\n<p>Die Datenverarbeitung erfolgt auf Grundlage von Art. 6 Abs. 1 lit. f DSGVO. Der Websitebetreiber hat ein berechtigtes Interesse daran, seine Webangebote vor missbr\u00e4uchlicher automatisierter Aussp\u00e4hung und vor SPAM zu sch\u00fctzen.<\/p>\n<p>Weitere Informationen zu Google reCAPTCHA sowie die Datenschutzerkl\u00e4rung von Google entnehmen Sie folgenden Links: https:\/\/www.google.com\/intl\/de\/policies\/privacy\/ und https:\/\/www.google.com\/recaptcha\/intro\/android.html.<\/p>\n<p>5. Newsletter<br \/>\nNewsletterdaten<br \/>\nWenn Sie den auf der Website angebotenen Newsletter beziehen m\u00f6chten, ben\u00f6tigen wir von Ihnen eine E-Mail-Adresse sowie Informationen, welche uns die \u00dcberpr\u00fcfung gestatten, dass Sie der Inhaber der angegebenen E-Mail-Adresse sind und mit dem Empfang des Newsletters einverstanden sind. Weitere Daten werden nicht bzw. nur auf freiwilliger Basis erhoben. Diese Daten verwenden wir ausschlie\u00dflich f\u00fcr den Versand der angeforderten Informationen und geben diese nicht an Dritte weiter.<\/p>\n<p>Die Verarbeitung der in das Newsletteranmeldeformular eingegebenen Daten erfolgt ausschlie\u00dflich auf Grundlage Ihrer Einwilligung (Art. 6 Abs. 1 lit. a DSGVO). Die erteilte Einwilligung zur Speicherung der Daten, der E-Mail-Adresse sowie deren Nutzung zum Versand des Newsletters k\u00f6nnen Sie jederzeit widerrufen, etwa \u00fcber den &#8222;Austragen&#8220;-Link im Newsletter. Die Rechtm\u00e4\u00dfigkeit der bereits erfolgten Datenverarbeitungsvorg\u00e4nge bleibt vom Widerruf unber\u00fchrt.<\/p>\n<p>Die von Ihnen zum Zwecke des Newsletter-Bezugs bei uns hinterlegten Daten werden von uns bis zu Ihrer Austragung aus dem Newsletter gespeichert und nach der Abbestellung des Newsletters gel\u00f6scht. Daten, die zu anderen Zwecken bei uns gespeichert wurden (z.B. E-Mail-Adressen f\u00fcr den Mitgliederbereich) bleiben hiervon unber\u00fchrt.<\/p>\n<p>6. Plugins und Tools<br \/>\nYouTube<br \/>\nUnsere Website nutzt Plugins der von Google betriebenen Seite YouTube. Betreiber der Seiten ist die YouTube, LLC, 901 Cherry Ave., San Bruno, CA 94066, USA.<\/p>\n<p>Wenn Sie eine unserer mit einem YouTube-Plugin ausgestatteten Seiten besuchen, wird eine Verbindung zu den Servern von YouTube hergestellt. Dabei wird dem YouTube-Server mitgeteilt, welche unserer Seiten Sie besucht haben.<\/p>\n<p>Wenn Sie in Ihrem YouTube-Account eingeloggt sind, erm\u00f6glichen Sie YouTube, Ihr Surfverhalten direkt Ihrem pers\u00f6nlichen Profil zuzuordnen. Dies k\u00f6nnen Sie verhindern, indem Sie sich aus Ihrem YouTube-Account ausloggen.<\/p>\n<p>Die Nutzung von YouTube erfolgt im Interesse einer ansprechenden Darstellung unserer Online-Angebote. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar.<\/p>\n<p>Weitere Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von YouTube unter: https:\/\/www.google.de\/intl\/de\/policies\/privacy.<\/p>\n<p>Vimeo<br \/>\nUnsere Website nutzt Plugins des Videoportals Vimeo. Anbieter ist die Vimeo Inc., 555 West 18th Street, New York, New York 10011, USA.<\/p>\n<p>Wenn Sie eine unserer mit einem Vimeo-Plugin ausgestatteten Seiten besuchen, wird eine Verbindung zu den Servern von Vimeo hergestellt. Dabei wird dem Vimeo-Server mitgeteilt, welche unserer Seiten Sie besucht haben. Zudem erlangt Vimeo Ihre IP-Adresse. Dies gilt auch dann, wenn Sie nicht bei Vimeo eingeloggt sind oder keinen Account bei Vimeo besitzen. Die von Vimeo erfassten Informationen werden an den Vimeo-Server in den USA \u00fcbermittelt.<\/p>\n<p>Wenn Sie in Ihrem Vimeo-Account eingeloggt sind, erm\u00f6glichen Sie Vimeo, Ihr Surfverhalten direkt Ihrem pers\u00f6nlichen Profil zuzuordnen. Dies k\u00f6nnen Sie verhindern, indem Sie sich aus Ihrem Vimeo-Account ausloggen.<\/p>\n<p>Weitere Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von Vimeo unter: https:\/\/vimeo.com\/privacy.<\/p>\n<p>Google Maps<br \/>\nDiese Seite nutzt \u00fcber eine API den Kartendienst Google Maps. Anbieter ist die Google Inc., 1600 Amphitheatre Parkway, Mountain View, CA 94043, USA.<\/p>\n<p>Zur Nutzung der Funktionen von Google Maps ist es notwendig, Ihre IP Adresse zu speichern. Diese Informationen werden in der Regel an einen Server von Google in den USA \u00fcbertragen und dort gespeichert. Der Anbieter dieser Seite hat keinen Einfluss auf diese Daten\u00fcbertragung.<\/p>\n<p>Die Nutzung von Google Maps erfolgt im Interesse einer ansprechenden Darstellung unserer Online-Angebote und an einer leichten Auffindbarkeit der von uns auf der Website angegebenen Orte. Dies stellt ein berechtigtes Interesse im Sinne von Art. 6 Abs. 1 lit. f DSGVO dar.<\/p>\n<p>Mehr Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von Google: https:\/\/www.google.de\/intl\/de\/policies\/privacy\/.<\/p>\n<p>SoundCloud<br \/>\nAuf unseren Seiten k\u00f6nnen Plugins des sozialen Netzwerks SoundCloud (SoundCloud Limited, Berners House, 47-48 Berners Street, London W1T 3NF, Gro\u00dfbritannien.) integriert sein. Die SoundCloud-Plugins erkennen Sie an dem SoundCloud-Logo auf den betroffenen Seiten.<\/p>\n<p>Wenn Sie unsere Seiten besuchen, wird nach Aktivierung des Plugin eine direkte Verbindung zwischen Ihrem Browser und dem SoundCloud-Server hergestellt. SoundCloud erh\u00e4lt dadurch die Information, dass Sie mit Ihrer IP-Adresse unsere Seite besucht haben. Wenn Sie den \u201cLike-Button\u201d oder \u201cShare-Button\u201d anklicken w\u00e4hrend Sie in Ihrem SoundCloud- Benutzerkonto eingeloggt sind, k\u00f6nnen Sie die Inhalte unserer Seiten mit Ihrem SoundCloud-Profil verlinken und\/oder teilen. Dadurch kann SoundCloud Ihrem Benutzerkonto den Besuch unserer Seiten zuordnen. Wir weisen darauf hin, dass wir als Anbieter der Seiten keine Kenntnis vom Inhalt der \u00fcbermittelten Daten sowie deren Nutzung durch SoundCloud erhalten. Weitere Informationen hierzu finden Sie in der Datenschutzerkl\u00e4rung von SoundCloud unter: https:\/\/soundcloud.com\/pages\/privacy.<\/p>\n<p>Wenn Sie nicht w\u00fcnschen, dass SoundCloud den Besuch unserer Seiten Ihrem SoundCloud- Benutzerkonto zuordnet, loggen Sie sich bitte aus Ihrem SoundCloud-Benutzerkonto aus bevor Sie Inhalte des SoundCloud-Plugins aktivieren.<\/p>\n<p>Veoh<br \/>\nUnsere Website nutzt Plugins des Videoportals Veoh. Anbieter ist die FC2, 4730 South Fort Apache Road, Suite 300, Las Vegas, NV 89147, USA.<\/p>\n<p>Wenn Sie eine unserer mit einem Veoh-Plugin ausgestatteten Seiten besuchen, wird eine Verbindung zu den Servern von Veoh hergestellt. Dabei wird dem Veoh-Server mitgeteilt, welche unserer Seiten Sie besucht haben. Zudem erlangt Veoh Ihre IP-Adresse. Dies gilt auch dann, wenn Sie nicht bei Veoh eingeloggt sind oder keinen Account bei Veoh besitzen. Die von Veoh erfassten Informationen werden an den Veoh-Server in den USA \u00fcbermittelt.<\/p>\n<p>Wenn Sie in Ihrem Veoh-Account eingeloggt sind, erm\u00f6glichen Sie Veoh, Ihr Surfverhalten direkt Ihrem pers\u00f6nlichen Profil zuzuordnen. Dies k\u00f6nnen Sie verhindern, indem Sie sich aus Ihrem Veoh-Account ausloggen.<\/p>\n<p>Weitere Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von Veoh unter: http:\/\/www.veoh.com\/corporate\/privacypolicy.<\/p>\n<p>Dailymotion<br \/>\nUnsere Website nutzt Plugins des Videoportals Dailymotion. Anbieter ist Dailymotion, 140 boulevard Malesherbes, 75017 Paris, Frankreich.<\/p>\n<p>Wenn Sie eine unserer mit einem Dailymotion-Plugin ausgestatteten Seiten besuchen, wird eine Verbindung zu den Servern von Dailymotion hergestellt. Dabei wird dem Dailymotion-Server mitgeteilt, welche unserer Seiten Sie besucht haben. Zudem erlangt Dailymotion Ihre IP-Adresse. Dies gilt auch dann, wenn Sie nicht bei Dailymotion eingeloggt sind oder keinen Account bei Dailymotion besitzen.<\/p>\n<p>Wenn Sie in Ihrem Dailymotion-Account eingeloggt sind, erm\u00f6glichen Sie Dailymotion, Ihr Surfverhalten direkt Ihrem pers\u00f6nlichen Profil zuzuordnen. Dies k\u00f6nnen Sie verhindern, indem Sie sich aus Ihrem Dailymotion-Account ausloggen.<\/p>\n<p>Weitere Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von Dailymotion unter: https:\/\/www.dailymotion.com\/legal\/privacy.<\/p>\n<p>GitHub<br \/>\nUnsere Website nutzt Plugins des Online-Dienstes GitHub. Anbieter ist GitHub, Inc, 88 Colin P Kelly Jr St, San Francisco, CA 94107, USA.<\/p>\n<p>Wenn Sie eine unserer mit einem GitHub-Plugin ausgestatteten Seiten besuchen, wird eine Verbindung zu den Servern von GitHub hergestellt. Dabei wird dem GitHub-Server mitgeteilt, welche unserer Seiten Sie besucht haben. Zudem erlangt GitHub Ihre IP-Adresse. Dies gilt auch dann, wenn Sie nicht bei GitHub eingeloggt sind oder keinen Account bei GitHub besitzen. Die von GitHub erfassten Informationen werden an den GitHub-Server in den USA \u00fcbermittelt.<\/p>\n<p>Wenn Sie in Ihrem GitHub-Account eingeloggt sind, erm\u00f6glichen Sie GitHub, Ihr Surfverhalten direkt Ihrem pers\u00f6nlichen Profil zuzuordnen. Dies k\u00f6nnen Sie verhindern, indem Sie sich aus Ihrem GitHub-Account ausloggen.<\/p>\n<p>Weitere Informationen zum Umgang mit Nutzerdaten finden Sie in der Datenschutzerkl\u00e4rung von GitHub unter: https:\/\/help.github.com\/articles\/github-privacy-statement\/.<\/p>\n<p>7. Zahlungsanbieter<br \/>\nPayPal<br \/>\nAuf unserer Website bieten wir u.a. die Bezahlung via PayPal an. Anbieter dieses Zahlungsdienstes ist die PayPal (Europe) S.\u00e0.r.l. et Cie, S.C.A., 22-24 Boulevard Royal, L-2449 Luxembourg (im Folgenden \u201cPayPal\u201d).<\/p>\n<p>Wenn Sie die Bezahlung via PayPal ausw\u00e4hlen, werden die von Ihnen eingegebenen Zahlungsdaten an PayPal \u00fcbermittelt.<\/p>\n<p>Die \u00dcbermittlung Ihrer Daten an PayPal erfolgt auf Grundlage von Art. 6 Abs. 1 lit. a DSGVO (Einwilligung) und Art. 6 Abs. 1 lit. b DSGVO (Verarbeitung zur Erf\u00fcllung eines Vertrags). Sie haben die M\u00f6glichkeit, Ihre Einwilligung zur Datenverarbeitung jederzeit zu widerrufen. Ein Widerruf wirkt sich auf die Wirksamkeit von in der Vergangenheit liegenden Datenverarbeitungsvorg\u00e4ngen nicht aus.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf unserer &hellip; <a href=\"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/\" class=\"more-link\"><span class=\"screen-reader-text\">Datenschutzerkl\u00e4rung<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":12,"menu_order":2,"comment_status":"open","ping_status":"open","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Datenschutzerkl\u00e4rung - Lindenhausen-weil Reisen Spa\u00df macht<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Datenschutzerkl\u00e4rung - Lindenhausen-weil Reisen Spa\u00df macht\" \/>\n<meta property=\"og:description\" content=\"&nbsp; 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf unserer &hellip; Datenschutzerkl\u00e4rung weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/\" \/>\n<meta property=\"og:site_name\" content=\"Lindenhausen-weil Reisen Spa\u00df macht\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/Lindenhausen\/\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-20T10:16:42+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Maxilinde\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"17\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/\",\"url\":\"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/\",\"name\":\"Datenschutzerkl\u00e4rung - Lindenhausen-weil Reisen Spa\u00df macht\",\"isPartOf\":{\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#website\"},\"datePublished\":\"2015-04-17T13:09:14+00:00\",\"dateModified\":\"2018-05-20T10:16:42+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.lindenhausen.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00fcber mich\",\"item\":\"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Datenschutzerkl\u00e4rung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#website\",\"url\":\"https:\/\/www.lindenhausen.de\/blog\/\",\"name\":\"Lindenhausen-weil Reisen Spa\u00df macht\",\"description\":\"Reisen und Kreuzfahrten, Reiseberichte, Kreuzfahrtforum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lindenhausen.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Datenschutzerkl\u00e4rung - Lindenhausen-weil Reisen Spa\u00df macht","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/","og_locale":"de_DE","og_type":"article","og_title":"Datenschutzerkl\u00e4rung - Lindenhausen-weil Reisen Spa\u00df macht","og_description":"&nbsp; 1. Datenschutz auf einen Blick Allgemeine Hinweise Die folgenden Hinweise geben einen einfachen \u00dcberblick dar\u00fcber, was mit Ihren personenbezogenen Daten passiert, wenn Sie unsere Website besuchen. Personenbezogene Daten sind alle Daten, mit denen Sie pers\u00f6nlich identifiziert werden k\u00f6nnen. Ausf\u00fchrliche Informationen zum Thema Datenschutz entnehmen Sie unserer unter diesem Text aufgef\u00fchrten Datenschutzerkl\u00e4rung. Datenerfassung auf unserer &hellip; Datenschutzerkl\u00e4rung weiterlesen &rarr;","og_url":"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/","og_site_name":"Lindenhausen-weil Reisen Spa\u00df macht","article_publisher":"http:\/\/www.facebook.com\/Lindenhausen\/","article_modified_time":"2018-05-20T10:16:42+00:00","twitter_card":"summary_large_image","twitter_site":"@Maxilinde","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"17\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/","url":"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/","name":"Datenschutzerkl\u00e4rung - Lindenhausen-weil Reisen Spa\u00df macht","isPartOf":{"@id":"https:\/\/www.lindenhausen.de\/blog\/#website"},"datePublished":"2015-04-17T13:09:14+00:00","dateModified":"2018-05-20T10:16:42+00:00","breadcrumb":{"@id":"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/datenschutzerklaerung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lindenhausen.de\/blog\/"},{"@type":"ListItem","position":2,"name":"\u00fcber mich","item":"http:\/\/www.lindenhausen.de\/blog\/ueber-mich\/"},{"@type":"ListItem","position":3,"name":"Datenschutzerkl\u00e4rung"}]},{"@type":"WebSite","@id":"https:\/\/www.lindenhausen.de\/blog\/#website","url":"https:\/\/www.lindenhausen.de\/blog\/","name":"Lindenhausen-weil Reisen Spa\u00df macht","description":"Reisen und Kreuzfahrten, Reiseberichte, Kreuzfahrtforum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lindenhausen.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages\/381"}],"collection":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/comments?post=381"}],"version-history":[{"count":3,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages\/381\/revisions"}],"predecessor-version":[{"id":3840,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages\/381\/revisions\/3840"}],"up":[{"embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages\/12"}],"wp:attachment":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/media?parent=381"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}