{"id":2614,"date":"2017-08-27T21:01:23","date_gmt":"2017-08-27T19:01:23","guid":{"rendered":"http:\/\/www.lindenhausen.de\/blog\/?page_id=2614"},"modified":"2017-08-27T21:27:37","modified_gmt":"2017-08-27T19:27:37","slug":"geiranger-24-07-2017","status":"publish","type":"page","link":"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/","title":{"rendered":"Geiranger 24.07.2017"},"content":{"rendered":"<p>6:00 Uhr klingelte der Wecker, eine Unzeit f\u00fcr mich Nachteule. Aber der Blick auf den Balkon entsch\u00e4digte und sofort war ich hellwach.<br \/>\n15 Minuten sp\u00e4ter stand ich schon auf Deck um diese grandiose Landschaft zu bestaunen.<br \/>\nHeute fr\u00fchst\u00fcckten wir auch gleich hier am B\u00fcffet und trotzten an Deck der morgendlichen K\u00e4lte.<\/p>\n<p><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_93171-e1503859913666.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-2615\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_93171-e1503859913666-225x300.jpg\" alt=\"K800_IMG_9317\" width=\"225\" height=\"300\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_93171-e1503859913666-225x300.jpg 225w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_93171-e1503859913666.jpg 600w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><br \/>\nDann fanden wir uns p\u00fcnktlich am Treffpunkt ein, genossen noch einen Cappuccino und schon ging es los.<br \/>\nDie etwa 1 St\u00fcndige Busfahrt nach Herdalssetra war kurzweilig, die Landschaft wundersch\u00f6n und der Reiseleiter, der ausgezeichnet Deutsch sprach versorgte uns mit allen notwendigen Infos \u00fcber Land, Leute und Natur.<br \/>\nDer 300 Jahre alte Sommerbauernhof war ein wirklich romantisches Fleckchen Erde, direkt unterhalb der Schneegrenze gelegen. Hier widmete man sich der Herstellung von Ziegenk\u00e4se auf traditionelle Art, aber auch Bauern die Schafe oder Rinder haben bringen ihre Tiere den Sommer \u00fcber auf diese Weide. Hier arbeiten Jugendliche aus aller Welt in ihren Semesterferien.<br \/>\nEs war ar\u2026kalt, f\u00fcr mich als Sommermenschen, der sich bei 30\u00b0C erst richtig wohlf\u00fchlt war es fast Winter \ud83d\ude09 aber die Landschaft um uns herum entsch\u00e4digte.<br \/>\nIn dem Fluss hier kann man Lachs fangen und \u00fcberall gab es Blaubeeren.<\/p>\n<p><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01021.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-2585\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01021-300x199.jpg\" alt=\"K800_DSC_0102\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01021-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01021.jpg 906w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00881-e1503860033917.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-2584\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00881-e1503860033917-199x300.jpg\" alt=\"K800_DSC_0088\" width=\"199\" height=\"300\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00881-e1503860033917-199x300.jpg 199w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00881-e1503860033917.jpg 600w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00691.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-2582\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00691-300x199.jpg\" alt=\"K800_DSC_0069\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00691-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00691.jpg 906w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00821.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-2583\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00821-300x199.jpg\" alt=\"K800_DSC_0082\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00821-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00821.jpg 906w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00661.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-2581\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00661-300x199.jpg\" alt=\"K800_DSC_0066\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00661-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00661.jpg 906w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9440-e1503860075378.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-2520\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9440-e1503860075378-225x300.jpg\" alt=\"K800_IMG_9440\" width=\"225\" height=\"300\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9440-e1503860075378-225x300.jpg 225w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9440-e1503860075378.jpg 600w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9422-e1503860090146.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-2518\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9422-e1503860090146-225x300.jpg\" alt=\"K800_IMG_9422\" width=\"225\" height=\"300\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9422-e1503860090146-225x300.jpg 225w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9422-e1503860090146.jpg 600w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9405-e1503860017229.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-2517\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9405-e1503860017229-225x300.jpg\" alt=\"K800_IMG_9405\" width=\"225\" height=\"300\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9405-e1503860017229-225x300.jpg 225w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9405-e1503860017229.jpg 600w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><br \/>\nDer Reiseleiter hatte auf diesem eher engen Feldweg den Busfahrer angewiesen r\u00fcckw\u00e4rts bis zu einer Wendestelle zu fahren, dieser war wohl anderer Meinung, wendete den Bus und sa\u00df dann prompt mit dem Heck im Stra\u00dfengraben. Der Bus lag in der Mitte auf, keine Chance ohne Hilfe hier herauszukommen.<br \/>\nUnd da es in Herdalssetra auch weder Handyempfang noch Internet noch Telefonleitungen gibt musste die Sattelitenverbindung im Ziegenstall benutzt werden.<br \/>\nF\u00fcr einige der Kids eine ganz neue Erfahrung.<br \/>\nNach 1 Stunde kam dann ein Abschlepper und kurz darauf der Bus einer Italienischen Gruppe von Costa, deren Bus wir in Beschlag nahmen in der Hoffnung das sie dann nach einer weiteren Stunde unseren Ersatzbus bekamen.<\/p>\n<p><div id='gallery-1' class='gallery galleryid-2614 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9453-e1503860209326.jpg'><img width=\"300\" height=\"225\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9453-e1503860209326-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9453-e1503860209326-300x225.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9453-e1503860209326.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00661.jpg'><img width=\"300\" height=\"199\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00661-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00661-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00661.jpg 906w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00821.jpg'><img width=\"300\" height=\"199\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00821-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00821-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00821.jpg 906w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00691.jpg'><img width=\"300\" height=\"199\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00691-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00691-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_00691.jpg 906w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9430-e1503860197195.jpg'><img width=\"300\" height=\"225\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9430-e1503860197195-300x225.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9430-e1503860197195-300x225.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9430-e1503860197195.jpg 800w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<br \/>\nWir fuhren zur\u00fcck zur Adlerstra\u00dfe und bewunderten den herrlichen Blick auf das Geirangerfjord und unser Schiff.<br \/>\nWir suchten noch einen Souvenirladen auf um zu einem horrenden Preis einen K\u00fchlschrankmagneten zu erwerben.<br \/>\nDanach per Tenderboot zur Costa Favolosa, um dann die Fahrt durch den Geiranger bei herrlichem Sonnenschein zu genie\u00dfen.<\/p>\n<p><div id='gallery-2' class='gallery galleryid-2614 gallery-columns-3 gallery-size-medium'><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01161.jpg'><img width=\"300\" height=\"199\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01161-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01161-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01161.jpg 906w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01191-e1503860313139.jpg'><img width=\"199\" height=\"300\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01191-e1503860313139-199x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01191-e1503860313139-199x300.jpg 199w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01191-e1503860313139.jpg 600w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01201.jpg'><img width=\"300\" height=\"199\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01201-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01201-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01201.jpg 906w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01271-e1503860325730.jpg'><img width=\"199\" height=\"300\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01271-e1503860325730-199x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01271-e1503860325730-199x300.jpg 199w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01271-e1503860325730.jpg 600w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01301.jpg'><img width=\"300\" height=\"199\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01301-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01301-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01301.jpg 906w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon landscape'>\n\t\t\t\t<a href='http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01441.jpg'><img width=\"300\" height=\"199\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01441-300x199.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01441-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01441.jpg 906w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a>\n\t\t\t<\/div><\/figure><figure class='gallery-item'>\n\t\t\t<div class='gallery-icon portrait'>\n\t\t\t\t<a href='http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01351-e1503860340884.jpg'><img width=\"199\" height=\"300\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01351-e1503860340884-199x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" decoding=\"async\" loading=\"lazy\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01351-e1503860340884-199x300.jpg 199w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_DSC_01351-e1503860340884.jpg 600w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/a>\n\t\t\t<\/div><\/figure>\n\t\t<\/div>\n<br \/>\nIn Hellesylt nahmen wir die Ausfl\u00fcgler wieder an Bord und dann ging es weiter durch die sch\u00f6ne Landschaft Norwegens.<br \/>\nWir hatten f\u00fcr den n\u00e4chsten Tag den speziellen Ausflug f\u00fcr die Diamant Pearls gebucht, im Today war keine Uhrzeit f\u00fcr den Treffpunkt angegeben, also statteten wir der Rezeption noch einen Besuch ab, dort wurde auch schnell Auskunft gegeben, sehr freundlich und ohne Wartezeit.<br \/>\nDer Sonnenuntergang heute war spektakul\u00e4r, auch wenn es nicht ganz dunkel wurde.<\/p>\n<p><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9584-e1503860443178.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-2523\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9584-e1503860443178-225x300.jpg\" alt=\"Sonnenuntergang\" width=\"225\" height=\"300\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9584-e1503860443178-225x300.jpg 225w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9584-e1503860443178.jpg 600w\" sizes=\"(max-width: 225px) 100vw, 225px\" \/><\/a><br \/>\nUnseren Absacker nahmen wir in der Wein Bar, um gegen Mitternacht ins Bett zu sinken denn auch morgen war der Treffpunkt recht fr\u00fch, 8:15.<\/p>\n<p>&nbsp;<\/p>\n<p><a title=\"Bergen 25.07.2017\" href=\"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/bergen-25-07-2017\/\">Hier geht es weiter<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>6:00 Uhr klingelte der Wecker, eine Unzeit f\u00fcr mich Nachteule. Aber der Blick auf den Balkon entsch\u00e4digte und sofort war ich hellwach. 15 Minuten sp\u00e4ter stand ich schon auf Deck um diese grandiose Landschaft zu bestaunen. Heute fr\u00fchst\u00fcckten wir auch gleich hier am B\u00fcffet und trotzten an Deck der morgendlichen K\u00e4lte. Dann fanden wir uns &hellip; <a href=\"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/\" class=\"more-link\"><span class=\"screen-reader-text\">Geiranger 24.07.2017<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":2328,"menu_order":3,"comment_status":"open","ping_status":"open","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Geiranger 24.07.2017 - Lindenhausen-weil Reisen Spa\u00df macht<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geiranger 24.07.2017 - Lindenhausen-weil Reisen Spa\u00df macht\" \/>\n<meta property=\"og:description\" content=\"6:00 Uhr klingelte der Wecker, eine Unzeit f\u00fcr mich Nachteule. Aber der Blick auf den Balkon entsch\u00e4digte und sofort war ich hellwach. 15 Minuten sp\u00e4ter stand ich schon auf Deck um diese grandiose Landschaft zu bestaunen. Heute fr\u00fchst\u00fcckten wir auch gleich hier am B\u00fcffet und trotzten an Deck der morgendlichen K\u00e4lte. Dann fanden wir uns &hellip; Geiranger 24.07.2017 weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Lindenhausen-weil Reisen Spa\u00df macht\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/Lindenhausen\/\" \/>\n<meta property=\"article:modified_time\" content=\"2017-08-27T19:27:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9453-e1503860209326-300x225.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Maxilinde\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/\",\"url\":\"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/\",\"name\":\"Geiranger 24.07.2017 - Lindenhausen-weil Reisen Spa\u00df macht\",\"isPartOf\":{\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#website\"},\"datePublished\":\"2017-08-27T19:01:23+00:00\",\"dateModified\":\"2017-08-27T19:27:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.lindenhausen.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reiseberichte Costa Kreuzfahrten\",\"item\":\"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Kreuzfahrten 2017\",\"item\":\"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Costa Favolosa 07.2017\",\"item\":\"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/\"},{\"@type\":\"ListItem\",\"position\":5,\"name\":\"Geiranger 24.07.2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#website\",\"url\":\"https:\/\/www.lindenhausen.de\/blog\/\",\"name\":\"Lindenhausen-weil Reisen Spa\u00df macht\",\"description\":\"Reisen und Kreuzfahrten, Reiseberichte, Kreuzfahrtforum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lindenhausen.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geiranger 24.07.2017 - Lindenhausen-weil Reisen Spa\u00df macht","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/","og_locale":"de_DE","og_type":"article","og_title":"Geiranger 24.07.2017 - Lindenhausen-weil Reisen Spa\u00df macht","og_description":"6:00 Uhr klingelte der Wecker, eine Unzeit f\u00fcr mich Nachteule. Aber der Blick auf den Balkon entsch\u00e4digte und sofort war ich hellwach. 15 Minuten sp\u00e4ter stand ich schon auf Deck um diese grandiose Landschaft zu bestaunen. Heute fr\u00fchst\u00fcckten wir auch gleich hier am B\u00fcffet und trotzten an Deck der morgendlichen K\u00e4lte. Dann fanden wir uns &hellip; Geiranger 24.07.2017 weiterlesen &rarr;","og_url":"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/","og_site_name":"Lindenhausen-weil Reisen Spa\u00df macht","article_publisher":"http:\/\/www.facebook.com\/Lindenhausen\/","article_modified_time":"2017-08-27T19:27:37+00:00","og_image":[{"url":"https:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2017\/08\/K800_IMG_9453-e1503860209326-300x225.jpg"}],"twitter_card":"summary_large_image","twitter_site":"@Maxilinde","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/","url":"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/","name":"Geiranger 24.07.2017 - Lindenhausen-weil Reisen Spa\u00df macht","isPartOf":{"@id":"https:\/\/www.lindenhausen.de\/blog\/#website"},"datePublished":"2017-08-27T19:01:23+00:00","dateModified":"2017-08-27T19:27:37+00:00","breadcrumb":{"@id":"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/geiranger-24-07-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lindenhausen.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Reiseberichte Costa Kreuzfahrten","item":"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/"},{"@type":"ListItem","position":3,"name":"Kreuzfahrten 2017","item":"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/"},{"@type":"ListItem","position":4,"name":"Costa Favolosa 07.2017","item":"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/kreuzfahrten-2017\/costa-favolosa-07-2017\/"},{"@type":"ListItem","position":5,"name":"Geiranger 24.07.2017"}]},{"@type":"WebSite","@id":"https:\/\/www.lindenhausen.de\/blog\/#website","url":"https:\/\/www.lindenhausen.de\/blog\/","name":"Lindenhausen-weil Reisen Spa\u00df macht","description":"Reisen und Kreuzfahrten, Reiseberichte, Kreuzfahrtforum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lindenhausen.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages\/2614"}],"collection":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/comments?post=2614"}],"version-history":[{"count":2,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages\/2614\/revisions"}],"predecessor-version":[{"id":2625,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages\/2614\/revisions\/2625"}],"up":[{"embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages\/2328"}],"wp:attachment":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/media?parent=2614"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}