{"id":1234,"date":"2015-10-21T20:55:34","date_gmt":"2015-10-21T18:55:34","guid":{"rendered":"http:\/\/www.lindenhausen.de\/blog\/?page_id=1234"},"modified":"2015-11-22T10:58:22","modified_gmt":"2015-11-22T09:58:22","slug":"toulon","status":"publish","type":"page","link":"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/","title":{"rendered":"Toulon"},"content":{"rendered":"<p style=\"text-align: left;\">11.09. 2015<br \/>\nHeute musste der Wecker gestellt werden, der einzige bei Costa gebuchte Ausflug sollte uns nach St. Tropez f\u00fchren. Milli ist ein Fan von Louis De Funes und so sollte es heute an den Schauplatz einiger seiner Filme gehen.<\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1342.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1161\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1342-300x199.jpg\" alt=\"Toulon Hafen\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1342-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1342-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1342.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\nVorher aber , da wir eh fr\u00fch dran waren, ins Restaurant Cetara. Hier gibt es kein zus\u00e4tzliches B\u00fcffet, alle Speisen werden gebracht. Sofort wenn man Platz nimmt werden Kaffee und S\u00e4fte angeboten, Tee kann man sich bestellen. Br\u00f6tchen, Butter und Marmelade werden eingesetzt, S\u00fc\u00dfe Teilchen direkt angeboten. Alles andere, von Eggs Benedict bis zur Wurstscheibe kann man sich aus der Karte bestellen. Ein sehr angenehmer Morgen mit einem aufmerksamen Serviceteam.<br \/>\nEin Experience Ausflug, die kleine Gruppe war dann aber doch eine Gro\u00dfe, da der Ausflug f\u00fcr die Deutsch \u2013und Englisch sprachigen G\u00e4ste durchgef\u00fchrt wurde. Ein Reiseleiter, der also alles in zwei Sprachen \u00fcbersetzen musste und dementsprechend ununterbrochen redete.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1344.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1162\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1344-300x199.jpg\" alt=\"Toulon\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1344-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1344-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1344.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1349.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1163\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1349-300x199.jpg\" alt=\"Stra\u00dfe\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1349-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1349-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1349.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\nMit dem Bus ging es, nachdem endlich alle G\u00e4ste da waren und ihr Ticket gefunden hatten, direkt nach St. Tropez,gef\u00fcttert mit vielen Informationen \u00fcber Korkgewinnung, Land und Leute, unser Reiseleiter war da recht fleissig. Dann eine einst\u00fcndige Stadtf\u00fchrung und danach 50 min Freizeit. Sehr wenig, was der Unp\u00fcnktlichkeit von G\u00e4sten, hundert Zwischenfragen und warten auf die \u201eNichtzuh\u00f6rer\u201c geschuldet war.<br \/>\nEs war wenig wieder zu finden, dennoch, ein ganz netter Ort, nicht so abgehoben wie Nizza oder Monte Carlo, eine gute Mischung aus Jet Set und uns \u201eNormalos\u201c.<\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1399.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"size-medium wp-image-1173 alignleft\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1399-300x199.jpg\" alt=\"St. Tropez 10\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1399-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1399-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1399.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1393.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1172\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1393-300x199.jpg\" alt=\"St. Tropez 9\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1393-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1393-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1393.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1389.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1171\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1389-300x199.jpg\" alt=\"St. Tropez 8\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1389-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1389-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1389.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1386-e1445453060363.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1170\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1386-e1445453060363-199x300.jpg\" alt=\"St. Tropez 7\" width=\"199\" height=\"300\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1386-e1445453060363-199x300.jpg 199w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1386-e1445453060363-678x1024.jpg 678w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1386-e1445453060363.jpg 768w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1381.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1169\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1381-300x199.jpg\" alt=\"St.Tropez 6\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1381-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1381-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1381.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1375.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1168\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1375-300x199.jpg\" alt=\"St. Tropez5\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1375-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1375-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1375.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1369.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1167\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1369-300x199.jpg\" alt=\"St. Tropez4\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1369-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1369-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1369.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1367.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1166\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1367-300x199.jpg\" alt=\"St. Tropez 3\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1367-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1367-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1367.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1362.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1165\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1362-300x199.jpg\" alt=\"St. Tropez2\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1362-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1362-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1362.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1360.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1164\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1360-300x199.jpg\" alt=\"St. Tropez 1\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1360-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1360-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1360.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\nNach dem Mittag dann ging es weiter nach Port Grimaud, entstanden in einem Sumpfgebiet, aus der Idee eines Architekten der ein zweites Venedig bauen wollte. 2500 Geb\u00e4ude die nie baugleich sind, alle Grundst\u00fccke mit dem Auto und dem Boot zu erreichen und-f\u00fcr mich das einzige was mit Venedig zu tun hat- alles Pfahlbauten.<br \/>\nSehr nett anzuschauen, bei Preisen von 60m2 ab 800000\u20ac dann aber nicht interessant, ich bleibe auf meiner gro\u00dfen Yacht.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1418.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1177\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1418-300x199.jpg\" alt=\"Grimaud4\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1418-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1418-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1418.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1417.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1176\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1417-300x199.jpg\" alt=\"Grimaud3\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1417-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1417-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1417.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1413.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1175\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1413-300x199.jpg\" alt=\"Grimaud2\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1413-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1413-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1413.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a> <a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1412.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1174\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1412-300x199.jpg\" alt=\"Grimaud1\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1412-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1412-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1412.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\nNicht ganz staufrei erreichten wir das Schiff wieder, genossen die Ausfahrt bei einem Spritz Venexiano und gingen dann zum Abendessen.<br \/>\nVon Toulon selber haben wir nichts gesehen, au\u00dfer das Rugby-Stadion-Toulon ist amtierender Europameister.<\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1427.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1178\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1427-300x199.jpg\" alt=\"auslaufenToulon\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1427-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1427-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1427.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\nDa in Toulon die gr\u00f6\u00dfte Kriegsmarinebasis Frankreichs liegt waren hier einige Kriegsschiffe, ein Flugzeugtr\u00e4ger und U-Boote zu sehen, auch w\u00e4hrend dem Abendessen begleitete uns ein U-Boot das dann auf Tauchfahrt ging.<\/p>\n<p style=\"text-align: left;\"><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1430.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1179\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1430-300x199.jpg\" alt=\"Abendessen1\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1430-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1430-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1430.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1432.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1180\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1432-300x199.jpg\" alt=\"Abendessen2\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1432-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1432-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1432.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1433.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1181\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1433-300x199.jpg\" alt=\"Abendessen3\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1433-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1433-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1433.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1434.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1182\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1434-300x199.jpg\" alt=\"Abendessen4\" width=\"300\" height=\"199\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1434-300x199.jpg 300w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1434-1024x678.jpg 1024w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1434.jpg 1160w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/a><br \/>\nDanach schauten wir kurz in der Show vorbei, mit den gro\u00dfen Costa Schiffen nicht vergleichbar, da fehlt es nat\u00fcrlich an B\u00fchnentechnik und M\u00f6glichkeiten.<br \/>\nEin Schwenk durch die Gand Bar und Absacker auf Deck 11 unter Sternenhimmel schlossen diesen sch\u00f6nen ersten Tag.<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1443-e1445453463929.jpg\"><img decoding=\"async\" loading=\"lazy\" class=\"aligncenter size-medium wp-image-1183\" src=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1443-e1445453463929-199x300.jpg\" alt=\"Abend\" width=\"199\" height=\"300\" srcset=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1443-e1445453463929-199x300.jpg 199w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1443-e1445453463929-678x1024.jpg 678w, http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1443-e1445453463929.jpg 768w\" sizes=\"(max-width: 199px) 100vw, 199px\" \/><\/a><\/p>\n<p style=\"text-align: left;\">In der Kabine dann ein Schreiben: Routen\u00e4nderung, statt nach Propriano geht es nach Ajaccio, es gibt wohl Probleme mit dem Wind.<\/p>\n<p style=\"text-align: center;\"><a title=\"Ajaccio\" href=\"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/ajaccio\/\">weiter nach Ajaccio<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>11.09. 2015 Heute musste der Wecker gestellt werden, der einzige bei Costa gebuchte Ausflug sollte uns nach St. Tropez f\u00fchren. Milli ist ein Fan von Louis De Funes und so sollte es heute an den Schauplatz einiger seiner Filme gehen. Vorher aber , da wir eh fr\u00fch dran waren, ins Restaurant Cetara. Hier gibt es &hellip; <a href=\"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/\" class=\"more-link\"><span class=\"screen-reader-text\">Toulon<\/span> weiterlesen <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1131,"menu_order":2,"comment_status":"open","ping_status":"open","template":"","meta":{"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Toulon - Lindenhausen-weil Reisen Spa\u00df macht<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Toulon - Lindenhausen-weil Reisen Spa\u00df macht\" \/>\n<meta property=\"og:description\" content=\"11.09. 2015 Heute musste der Wecker gestellt werden, der einzige bei Costa gebuchte Ausflug sollte uns nach St. Tropez f\u00fchren. Milli ist ein Fan von Louis De Funes und so sollte es heute an den Schauplatz einiger seiner Filme gehen. Vorher aber , da wir eh fr\u00fch dran waren, ins Restaurant Cetara. Hier gibt es &hellip; Toulon weiterlesen &rarr;\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/\" \/>\n<meta property=\"og:site_name\" content=\"Lindenhausen-weil Reisen Spa\u00df macht\" \/>\n<meta property=\"article:publisher\" content=\"http:\/\/www.facebook.com\/Lindenhausen\/\" \/>\n<meta property=\"article:modified_time\" content=\"2015-11-22T09:58:22+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1342-300x199.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@Maxilinde\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/\",\"url\":\"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/\",\"name\":\"Toulon - Lindenhausen-weil Reisen Spa\u00df macht\",\"isPartOf\":{\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#website\"},\"datePublished\":\"2015-10-21T18:55:34+00:00\",\"dateModified\":\"2015-11-22T09:58:22+00:00\",\"breadcrumb\":{\"@id\":\"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.lindenhausen.de\/blog\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Reiseberichte Costa Kreuzfahrten\",\"item\":\"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Costa neoRiviera 09.2015\",\"item\":\"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Toulon\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lindenhausen.de\/blog\/#website\",\"url\":\"https:\/\/www.lindenhausen.de\/blog\/\",\"name\":\"Lindenhausen-weil Reisen Spa\u00df macht\",\"description\":\"Reisen und Kreuzfahrten, Reiseberichte, Kreuzfahrtforum\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lindenhausen.de\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Toulon - Lindenhausen-weil Reisen Spa\u00df macht","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/","og_locale":"de_DE","og_type":"article","og_title":"Toulon - Lindenhausen-weil Reisen Spa\u00df macht","og_description":"11.09. 2015 Heute musste der Wecker gestellt werden, der einzige bei Costa gebuchte Ausflug sollte uns nach St. Tropez f\u00fchren. Milli ist ein Fan von Louis De Funes und so sollte es heute an den Schauplatz einiger seiner Filme gehen. Vorher aber , da wir eh fr\u00fch dran waren, ins Restaurant Cetara. Hier gibt es &hellip; Toulon weiterlesen &rarr;","og_url":"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/","og_site_name":"Lindenhausen-weil Reisen Spa\u00df macht","article_publisher":"http:\/\/www.facebook.com\/Lindenhausen\/","article_modified_time":"2015-11-22T09:58:22+00:00","og_image":[{"url":"http:\/\/www.lindenhausen.de\/blog\/wp-content\/uploads\/2015\/10\/K1024_DSC_1342-300x199.jpg"}],"twitter_card":"summary_large_image","twitter_site":"@Maxilinde","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/","url":"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/","name":"Toulon - Lindenhausen-weil Reisen Spa\u00df macht","isPartOf":{"@id":"https:\/\/www.lindenhausen.de\/blog\/#website"},"datePublished":"2015-10-21T18:55:34+00:00","dateModified":"2015-11-22T09:58:22+00:00","breadcrumb":{"@id":"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/toulon\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lindenhausen.de\/blog\/"},{"@type":"ListItem","position":2,"name":"Reiseberichte Costa Kreuzfahrten","item":"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/"},{"@type":"ListItem","position":3,"name":"Costa neoRiviera 09.2015","item":"https:\/\/www.lindenhausen.de\/blog\/reiseberichte-costa\/costa-neoriviera-09-2015\/"},{"@type":"ListItem","position":4,"name":"Toulon"}]},{"@type":"WebSite","@id":"https:\/\/www.lindenhausen.de\/blog\/#website","url":"https:\/\/www.lindenhausen.de\/blog\/","name":"Lindenhausen-weil Reisen Spa\u00df macht","description":"Reisen und Kreuzfahrten, Reiseberichte, Kreuzfahrtforum","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lindenhausen.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages\/1234"}],"collection":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/comments?post=1234"}],"version-history":[{"count":5,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages\/1234\/revisions"}],"predecessor-version":[{"id":1509,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages\/1234\/revisions\/1509"}],"up":[{"embeddable":true,"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/pages\/1131"}],"wp:attachment":[{"href":"http:\/\/www.lindenhausen.de\/blog\/wp-json\/wp\/v2\/media?parent=1234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}